{"id":12069,"date":"2025-09-26T14:22:00","date_gmt":"2025-09-26T17:22:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=12069"},"modified":"2025-09-26T11:21:44","modified_gmt":"2025-09-26T14:21:44","slug":"comunicado-do-itau-atinge-20-mil-pessoas-com-demissao-em-massa","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/comunicado-do-itau-atinge-20-mil-pessoas-com-demissao-em-massa\/","title":{"rendered":"Comunicado do Ita\u00fa atinge 20 mil pessoas com demiss\u00e3o em massa"},"content":{"rendered":"\n<p>O Ita\u00fa anunciou o encerramento das atividades de uma ag\u00eancia localizada na rua Tancredo Neves, no bairro Caminho das \u00c1rvores, em Salvador. De acordo com a Federa\u00e7\u00e3o dos Banc\u00e1rios da Bahia e Sergipe (Feebbase), a decis\u00e3o vai impactar diretamente cerca de 20 mil clientes e 28 funcion\u00e1rios que atuavam na unidade.<\/p>\n\n\n\n<p>O fechamento faz parte de um processo de reestrutura\u00e7\u00e3o que o banco j\u00e1 vinha implementando em diferentes regi\u00f5es do pa\u00eds. A institui\u00e7\u00e3o tem direcionado esfor\u00e7os para a expans\u00e3o de seus canais digitais, respons\u00e1veis por aproximadamente 97% das transa\u00e7\u00f5es realizadas por pessoas f\u00edsicas.<\/p>\n\n\n\n<p>Em Salvador, n\u00e3o \u00e9 a primeira vez que o banco promove cortes dessa natureza. Ag\u00eancias nos bairros de Brotas, Cabula e Imbu\u00ed tamb\u00e9m encerraram suas atividades recentemente, em um movimento que j\u00e1 afetou cerca de 73 mil clientes.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"12070\" src=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/09\/2023-02-02T121545Z_1_LYNXMPEJ110JT_RTROPTP_4_CHILE-ECONOMY.jpg\" alt=\"\" class=\"wp-image-12070\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos; Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Demiss\u00f5es em massa e justificativas apresentadas<\/h2>\n\n\n\n<p>Al\u00e9m do fechamento de ag\u00eancias, o Ita\u00fa tamb\u00e9m realizou demiss\u00f5es em larga escala. No in\u00edcio de setembro, aproximadamente mil funcion\u00e1rios foram desligados em S\u00e3o Paulo, segundo informa\u00e7\u00f5es do Sindicato dos Banc\u00e1rios da capital paulista.&nbsp;<\/p>\n\n\n\n<p>O epis\u00f3dio gerou debates sobre os crit\u00e9rios utilizados pela institui\u00e7\u00e3o e os impactos no quadro de colaboradores. Em nota enviada \u00e0 imprensa, o banco afirmou que os desligamentos ocorreram ap\u00f3s uma revis\u00e3o interna sobre condutas relacionadas ao trabalho remoto e ao registro de jornada.&nbsp;<\/p>\n\n\n\n<p>O comunicado destacou que foram identificados padr\u00f5es considerados incompat\u00edveis com os princ\u00edpios de confian\u00e7a adotados pelo Ita\u00fa. A institui\u00e7\u00e3o classificou as medidas como parte de uma gest\u00e3o respons\u00e1vel, que busca preservar sua cultura organizacional e manter a credibilidade junto aos clientes e \u00e0 sociedade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Ita\u00fa anunciou o encerramento das atividades de uma ag\u00eancia localizada na rua Tancredo Neves, no bairro Caminho das \u00c1rvores, em Salvador. De acordo com a Federa\u00e7\u00e3o dos Banc\u00e1rios da Bahia e Sergipe (Feebbase), a decis\u00e3o vai impactar diretamente cerca de 20 mil clientes e 28 funcion\u00e1rios que atuavam na unidade. O fechamento faz parte [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12069","post","type-post","status-publish","format-standard","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/12069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=12069"}],"version-history":[{"count":1,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/12069\/revisions"}],"predecessor-version":[{"id":12072,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/12069\/revisions\/12072"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=12069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=12069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=12069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}