{"id":19416,"date":"2025-11-20T13:45:00","date_gmt":"2025-11-20T16:45:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=19416"},"modified":"2025-11-21T16:00:15","modified_gmt":"2025-11-21T19:00:15","slug":"moto-homenageando-senna-vendeu-todas-as-unidades-em-menos-de-24-horas","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/moto-homenageando-senna-vendeu-todas-as-unidades-em-menos-de-24-horas\/","title":{"rendered":"Moto homenageando Senna vendeu todas as unidades em menos de 24 horas"},"content":{"rendered":"\n<p>Em 2024, a Ducati lan\u00e7ou uma edi\u00e7\u00e3o especial da Monster 900 em homenagem a Ayrton Senna, tr\u00eas d\u00e9cadas ap\u00f3s o falecimento do piloto brasileiro. A motocicleta, chamada Ducati Monster Senna, foi desenvolvida para celebrar a trajet\u00f3ria de um dos maiores nomes da F\u00f3rmula 1 e trazer elementos do legado de Senna para o universo das duas rodas.<\/p>\n\n\n\n<p>A iniciativa destacou a import\u00e2ncia de manter viva a mem\u00f3ria de pilotos hist\u00f3ricos em cole\u00e7\u00f5es e ve\u00edculos especiais. Foram produzidas apenas 341 unidades em todo o mundo, tornando a moto extremamente rara. No Brasil, a quantidade dispon\u00edvel foi ainda mais limitada, com apenas 41 unidades \u00e0 venda.<\/p>\n\n\n\n<p>Toda a produ\u00e7\u00e3o nacional esgotou em menos de 24 horas, demonstrando a for\u00e7a da marca Senna entre f\u00e3s de automobilismo e colecionadores. A velocidade com que as unidades foram vendidas refor\u00e7a a relev\u00e2ncia do piloto no imagin\u00e1rio do p\u00fablico e a demanda por produtos exclusivos ligados ao seu legado.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"19417\" src=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/11\/Ducati-Panigale-S-Senna-15-Sorteio-1-1.jpg\" alt=\"\" class=\"wp-image-19417\"\/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Design e desempenho inspirados em Senna<\/h2>\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 12px;\n      height: 30px;\n      padding: 0 12px;\n      max-width: 160px;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/correiodoestado.com.br\/mix\/xodozinho-dos-brasileiros-uno-ressurge-com-versao-inspirada-nos-carros-de-formula-1\/?utm_source=lazy\" target=\"_blank\" rel=\"noopener\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2025\/11\/700_67d485ad37a1b-700x375.jpg\" data-src=\"https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2025\/11\/700_67d485ad37a1b-700x375.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>CE Mix<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Uno renasce na F1 \ud83c\udfc1<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Nova vers\u00e3o inspira f\u00e3s do cl\u00e1ssico<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Confira agora<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/correiodoestado.com.br\/mix\/xodozinho-dos-brasileiros-uno-ressurge-com-versao-inspirada-nos-carros-de-formula-1\/?utm_source=lazy\" target=\"_blank\" rel=\"noopener\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2025\/11\/700_67d485ad37a1b-700x375.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Uno renasce na F1 \ud83c\udfc1<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Confira agora<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n\n\n\n<p>O design da Monster Senna foi pensado para remeter ao capacete ic\u00f4nico do piloto. A pintura combina cores amarela, verde e azul, enquanto o banco azul reproduz detalhes de alguns modelos de capacete usados por Senna durante sua carreira.<\/p>\n\n\n\n<p>Al\u00e9m da est\u00e9tica, a moto apresenta motor de 937 cc com dois cilindros e 111 cv de pot\u00eancia, oferecendo desempenho elevado e experi\u00eancia de pilotagem intensa. Entre os destaques da edi\u00e7\u00e3o est\u00e3o sistemas de freio ABS com tr\u00eas n\u00edveis de ajuste, controle de tra\u00e7\u00e3o e freios Brembo de alta performance.<\/p>\n\n\n\n<p>O peso total da moto \u00e9 quatro quilos inferior \u00e0 vers\u00e3o padr\u00e3o, o que proporciona maior agilidade e condu\u00e7\u00e3o mais din\u00e2mica. Cada detalhe refor\u00e7a a liga\u00e7\u00e3o entre a performance do piloto e o desempenho da motocicleta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2024, a Ducati lan\u00e7ou uma edi\u00e7\u00e3o especial da Monster 900 em homenagem a Ayrton Senna, tr\u00eas d\u00e9cadas ap\u00f3s o falecimento do piloto brasileiro. A motocicleta, chamada Ducati Monster Senna, foi desenvolvida para celebrar a trajet\u00f3ria de um dos maiores nomes da F\u00f3rmula 1 e trazer elementos do legado de Senna para o universo das [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19416","post","type-post","status-publish","format-standard","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/19416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=19416"}],"version-history":[{"count":2,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/19416\/revisions"}],"predecessor-version":[{"id":20195,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/19416\/revisions\/20195"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=19416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=19416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=19416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}