{"id":21357,"date":"2025-11-28T18:50:00","date_gmt":"2025-11-28T21:50:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=21357"},"modified":"2025-11-28T17:13:36","modified_gmt":"2025-11-28T20:13:36","slug":"uma-das-rodovias-mais-movimentadas-do-brasil-tera-novo-pedagio-a-partir-de-6-de-dezembro","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/uma-das-rodovias-mais-movimentadas-do-brasil-tera-novo-pedagio-a-partir-de-6-de-dezembro\/","title":{"rendered":"Uma das rodovias mais movimentadas do Brasil ter\u00e1 novo ped\u00e1gio a partir de 6 de dezembro"},"content":{"rendered":"\n<p>A Rodovia Presidente Dutra, no trecho urbano em dire\u00e7\u00e3o ao Aeroporto Internacional de S\u00e3o Paulo, em Guarulhos, ter\u00e1 ped\u00e1gio eletr\u00f4nico Free Flow a partir de 6 de dezembro. O valor do ped\u00e1gio at\u00e9 o aeroporto ser\u00e1 de R$ 1,37, com pre\u00e7os proporcionais \u00e0 dist\u00e2ncia percorrida: Rodovia Fern\u00e3o Dias (R$ 0,25), Avenida Tiradentes (R$ 0,52), Bairro Bonsucesso (R$ 2,69), Bairro Pimentas (R$ 2,80) e Jardim Arac\u00edlia (R$ 2,82).&nbsp;<\/p>\n\n\n\n<p>O Free Flow \u00e9 um sistema de pagamento eletr\u00f4nico autom\u00e1tico, sem necessidade de parar. P\u00f3rticos instalados nas pistas expressas registram a passagem por tag ou leitura da placa e calculam o valor do trecho, que varia conforme dia, hor\u00e1rio da semana e feriados.<\/p>\n\n\n\n<p>Motoristas com tag t\u00eam d\u00e9bito autom\u00e1tico e desconto de 5%, enquanto quem n\u00e3o possui tag pode pagar em at\u00e9 30 dias pelo site pedagiodigital.com ou aplicativo da CCR. Totens de autoatendimento estar\u00e3o dispon\u00edveis nas bases de S\u00e3o Paulo e Aruj\u00e1. Motos pagam meia tarifa.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"21359\" src=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/11\/Captura-de-tela-2025-11-28-171125.png\" alt=\"\" class=\"wp-image-21359\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Reprodu\u00e7\u00e3o<br><\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Obras e melhorias na Dutra<\/h2>\n\n\n\n<p>A implanta\u00e7\u00e3o do ped\u00e1gio faz parte do contrato da CCR, vencido em leil\u00e3o em outubro de 2021, com valor de outorga de R$ 1,77 bilh\u00e3o. Para viabilizar a cobran\u00e7a, a concession\u00e1ria realizou obras no trecho urbano, que inclui bairros residenciais de S\u00e3o Paulo e Guarulhos.<\/p>\n\n\n\n<p>Entre as melhorias est\u00e3o a amplia\u00e7\u00e3o da pista expressa para tr\u00eas faixas por sentido, novo viaduto de acesso ao aeroporto, liga\u00e7\u00e3o com o viaduto do Tatuap\u00e9 e tr\u00eas novos viadutos de conex\u00e3o com a Rodovia Fern\u00e3o Dias.<\/p>\n\n\n\n<p>Tamb\u00e9m foi implantado um dispositivo de retorno na Jacu P\u00eassego, readequadas 27 passarelas e instalada nova ilumina\u00e7\u00e3o, aumentando a seguran\u00e7a. O acesso \u00e0 pista expressa ser\u00e1 sinalizado a partir do km 228,850, com placas indicando valores e destinos.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Rodovia Presidente Dutra, no trecho urbano em dire\u00e7\u00e3o ao Aeroporto Internacional de S\u00e3o Paulo, em Guarulhos, ter\u00e1 ped\u00e1gio eletr\u00f4nico Free Flow a partir de 6 de dezembro. O valor do ped\u00e1gio at\u00e9 o aeroporto ser\u00e1 de R$ 1,37, com pre\u00e7os proporcionais \u00e0 dist\u00e2ncia percorrida: Rodovia Fern\u00e3o Dias (R$ 0,25), Avenida Tiradentes (R$ 0,52), Bairro [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":21358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/21357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=21357"}],"version-history":[{"count":1,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/21357\/revisions"}],"predecessor-version":[{"id":21360,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/21357\/revisions\/21360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/21358"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=21357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=21357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=21357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}