{"id":21886,"date":"2025-12-02T20:30:00","date_gmt":"2025-12-02T23:30:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=21886"},"modified":"2025-12-02T19:33:07","modified_gmt":"2025-12-02T22:33:07","slug":"famosa-rede-com-quase-2-000-academias-vai-deixar-adolescentes-treinarem-de-graca-a-partir-de-agora","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/famosa-rede-com-quase-2-000-academias-vai-deixar-adolescentes-treinarem-de-graca-a-partir-de-agora\/","title":{"rendered":"Famosa rede com quase 2.000 academias vai deixar adolescentes treinarem de gra\u00e7a a partir de agora"},"content":{"rendered":"\n<p>A Smart Fit, atualmente com 1.867 unidades e em plena expans\u00e3o para alcan\u00e7ar 2.000 academias em 2025, lan\u00e7ou uma a\u00e7\u00e3o voltada diretamente para adolescentes de 14 a 18 anos em toda a Am\u00e9rica Latina.<\/p>\n\n\n\n<p>A iniciativa, chamada \u201cRol\u00ea na Smart\u201d, oferece acesso gratuito \u00e0s academias durante o per\u00edodo de f\u00e9rias, em hor\u00e1rios espec\u00edficos, como parte de um movimento da rede para estimular h\u00e1bitos de atividade f\u00edsica entre jovens.<\/p>\n\n\n\n<p>O acesso gratuito estar\u00e1 dispon\u00edvel entre 10h e 16h, permitindo que o p\u00fablico-alvo utilize os equipamentos de muscula\u00e7\u00e3o e cardio das unidades participantes. Para ingressar na a\u00e7\u00e3o, o adolescente deve realizar uma matr\u00edcula simples e preencher o PAR-Q, formul\u00e1rio padr\u00e3o que avalia condi\u00e7\u00f5es b\u00e1sicas de sa\u00fade.<\/p>\n\n\n\n<p>At\u00e9 os 17 anos, \u00e9 obrigat\u00f3rio o acompanhamento de um respons\u00e1vel durante o cadastro. J\u00e1 os jovens de 14 anos precisam apresentar atestado m\u00e9dico, enquanto aqueles a partir de 15 anos devem consultar o balc\u00e3o da unidade para verificar se a exig\u00eancia tamb\u00e9m se aplica \u00e0 sua regi\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" data-id=\"21887\" src=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/12\/5-exercicios-para-fortalecer-as-costas-156_widemd.jpg\" alt=\"\" class=\"wp-image-21887\" srcset=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/12\/5-exercicios-para-fortalecer-as-costas-156_widemd.jpg 900w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/12\/5-exercicios-para-fortalecer-as-costas-156_widemd-300x200.jpg 300w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/12\/5-exercicios-para-fortalecer-as-costas-156_widemd-768x512.jpg 768w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2025\/12\/5-exercicios-para-fortalecer-as-costas-156_widemd-750x500.jpg 750w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Shutterstock<br><\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Regras e funcionamento da iniciativa nas unidades<\/h2>\n\n\n\n<p>O programa vale para todos os pa\u00edses onde a Smart Fit atua, abrangendo 15 na\u00e7\u00f5es da Am\u00e9rica Latina. A estrutura das academias permanece a mesma, e o acesso gratuito n\u00e3o inclui modalidades extras que dependem de planos espec\u00edficos. Cada adolescente deve seguir as normas internas das unidades e respeitar as orienta\u00e7\u00f5es de seguran\u00e7a e uso dos equipamentos.<\/p>\n\n\n\n<p>Segundo a empresa, a proposta \u00e9 oferecer um espa\u00e7o onde os adolescentes possam desenvolver rotina de atividade f\u00edsica durante o per\u00edodo de f\u00e9rias, com est\u00edmulo \u00e0 conviv\u00eancia e ao uso respons\u00e1vel das academias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Smart Fit, atualmente com 1.867 unidades e em plena expans\u00e3o para alcan\u00e7ar 2.000 academias em 2025, lan\u00e7ou uma a\u00e7\u00e3o voltada diretamente para adolescentes de 14 a 18 anos em toda a Am\u00e9rica Latina. A iniciativa, chamada \u201cRol\u00ea na Smart\u201d, oferece acesso gratuito \u00e0s academias durante o per\u00edodo de f\u00e9rias, em hor\u00e1rios espec\u00edficos, como parte [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":21888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/21886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=21886"}],"version-history":[{"count":1,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/21886\/revisions"}],"predecessor-version":[{"id":21889,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/21886\/revisions\/21889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/21888"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=21886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=21886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=21886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}