{"id":4277,"date":"2025-08-09T13:00:00","date_gmt":"2025-08-09T16:00:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=4277"},"modified":"2025-08-05T19:05:29","modified_gmt":"2025-08-05T22:05:29","slug":"quem-vai-sacar-dinheiro-em-agosto-precisa-cuidar-esse-novo-golpe","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/quem-vai-sacar-dinheiro-em-agosto-precisa-cuidar-esse-novo-golpe\/","title":{"rendered":"Quem vai sacar dinheiro em agosto precisa cuidar esse novo golpe"},"content":{"rendered":"\n<p>Embora a maioria da popula\u00e7\u00e3o tenha adotado formas pr\u00e1ticas de realizar <a href=\"https:\/\/correiodoestado.com.br\/mix\/verdao-fecha-contratacao-do-atacante-dentinho\/\" target=\"_blank\" rel=\"noopener\">transfer\u00eancias <\/a>e receber dinheiro, outras pessoas preferem manter os costumes arcaicos em evid\u00eancia. Para aqueles que ainda seguem utilizando caixas eletr\u00f4nicos, \u00e9 necess\u00e1rio se atentar ao novo golpe que tem assolado v\u00e1rias regi\u00f5es do Brasil, o chamado &#8220;Golpe do Falso Suporte T\u00e9cnico&#8221;.<\/p>\n\n\n\n<p>De modo geral, a pr\u00e1tica dos criminosos consiste em colar adesivos com um n\u00famero de telefone 0800 falso em um\u00a0caixa eletr\u00f4nico. Naturalmente, quando problemas aparecem, m\u00ednimos que sejam, usu\u00e1rios s\u00e3o induzidos a contatarem uma &#8220;central de ajuda&#8221; fraudulenta, que pode zerar todo o saldo de sua conta e at\u00e9 mesmo realizar chantagens. <\/p>\n\n\n\n<p><strong>Mas afinal, como o golpe funciona na pr\u00e1tica?<\/strong><\/p>\n\n\n\n<p>Tudo come\u00e7a de forma planejada, sem que a v\u00edtima desconfie de qualquer transtorno. Em suma, o golpista gruda um adesivo de apar\u00eancia profissional com um n\u00famero de 0800 falso sobre os contatos de ajuda oficiais do banco no\u00a0caixa eletr\u00f4nico. Algumas vezes, ele pode servir para impossibilitar momentaneamente a sa\u00edda do dinheiro ou a entrada do cart\u00e3o, criando um problema real para o usu\u00e1rio.<\/p>\n\n\n\n<p>Nesse \u00ednterim, uma outra pessoa surge oferecendo &#8220;ajuda&#8221;, indicando j\u00e1 ter passado pelo mesmo problema, mas que resolveu contatando o n\u00famero fixado no caixa eletr\u00f4nico. Nessa hora, a v\u00edtima acaba ligando para o ramal em quest\u00e3o, onde um &#8220;t\u00e9cnico de suporte&#8221; passa as informa\u00e7\u00f5es necess\u00e1rias para que o golpe seja sacramentado.<\/p>\n\n\n\n<p>A fim de tornar a liga\u00e7\u00e3o profissional e longe de desconfian\u00e7a, o falso profissional pede para que uma s\u00e9rie de \u201ctestes para diagn\u00f3stico\u201d seja efetuada. Assim, o &#8220;funcion\u00e1rio&#8221; pode pedir que a v\u00edtima insira o cart\u00e3o e digite a senha \u201cpara verificar a conex\u00e3o\u201d ou que fa\u00e7a um\u00a0Pix\u00a0de baixo valor para uma \u201cconta de teste do banco\u201d. No mais, o dinheiro \u00e9 direcionado para a conta do golpista e o problema \u00e9 evidenciado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira outros golpes famosos e como evitar cair neles<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Golpes via Pix<\/strong>:<\/li>\n<\/ul>\n\n\n\n<p>Fazer transfer\u00eancias banc\u00e1rias de modo pr\u00e1tico somente foi potencializado gra\u00e7as a cria\u00e7\u00e3o do Pix, lan\u00e7ado em 2020. Apesar de ter revolucionado o ramo financeiro, a mesma facilidade explorat\u00f3ria beneficiou golpistas que se aproveitam da ingenuidade dos usu\u00e1rios. De modo geral, os criminosos costumam oferecer falsas ofertas de vendas, divulgadas em redes sociais.<a href=\"https:\/\/correiodoestado.com.br\/mix\/mulher-de-mano-brown-e-flagrada-aos-beijos-com-outra-mulher\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n\n\n\n<p>Ao encaminhar os dados banc\u00e1rios para que o dep\u00f3sito seja efetuado, as v\u00edtimas pagam o valor solicitado, mas as cifras s\u00e3o projetadas a uma conta fraudulenta. Assim, al\u00e9m de n\u00e3o recuperar o Pix efetuado, o produto sequer ser\u00e1 entregue em seu domic\u00edlio por simplesmente n\u00e3o existir.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Clonagem no WhatsApp:<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Talvez o golpe mais antigo da lista em quest\u00e3o, clonar WhatsApp passou a ser bastante frequente, principalmente aos usu\u00e1rios mais antigos que costumam abrir qualquer link encaminhado. Na a\u00e7\u00e3o em quest\u00e3o, os criminosos conseguem ter acesso ao perfil de terceiros, solicitando dinheiro emprestado para os contatos presentes na conta invadida.<\/p>\n\n\n\n<p>Diante da invas\u00e3o, os golpistas encaminham mensagem solicitando transfer\u00eancias aos contatos das v\u00edtimas, que na maioria das vezes acabam perdendo dinheiro. Assim, utilizam contas banc\u00e1rias diferentes para que o rastreio seja de dif\u00edcil acesso quando denunciado \u00e0s autoridades.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Boletos adulterados:<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Assim como os demais golpes, o do boleto alterado n\u00e3o tem como reaver o dinheiro transferido. Em suma, os golpistas utilizam programas que modificam a linha digit\u00e1vel dos boletos, redirecionando os pagamentos para contas de criminosos. O detalhe negativo \u00e9 que a mudan\u00e7a nos d\u00edgitos \u00e9 muitas vezes impercept\u00edvel ao usu\u00e1rio.<\/p>\n\n\n\n<p><strong>O que fazer para n\u00e3o cair em golpes?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Verifique sempre a autenticidade da fonte dos dados;<\/li>\n\n\n\n<li>Ao comprar em um site diferente, confira os dados da empresa em quest\u00e3o;<\/li>\n\n\n\n<li>Adicione a op\u00e7\u00e3o de verifica\u00e7\u00e3o de dois fatores em seu celular;<\/li>\n\n\n\n<li>N\u00e3o aperte em links encaminhados por pessoas que n\u00e3o estejam na lista de seus contatos;<\/li>\n\n\n\n<li>Caso possua, ative a op\u00e7\u00e3o de alerta de transa\u00e7\u00f5es at\u00edpicas, ajudando a interromper atividades suspeitas antes que causem maiores danos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Novo golpe do caixa eletr\u00f4nico \u00e9 evidenciado e liga sinal de alerta de pessoas idosas que s\u00e3o as maiores v\u00edtimas da quadrilha <\/p>\n","protected":false},"author":8,"featured_media":4286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=4277"}],"version-history":[{"count":3,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4277\/revisions"}],"predecessor-version":[{"id":4877,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/4277\/revisions\/4877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/4286"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=4277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=4277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=4277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}