{"id":43440,"date":"2026-05-13T06:15:00","date_gmt":"2026-05-13T09:15:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=43440"},"modified":"2026-05-12T15:43:16","modified_gmt":"2026-05-12T18:43:16","slug":"cidade-afunda-25-centimetros-e-estadio-que-recebera-jogos-da-copa-do-mundo-apresenta-rachaduras","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/cidade-afunda-25-centimetros-e-estadio-que-recebera-jogos-da-copa-do-mundo-apresenta-rachaduras\/","title":{"rendered":"Cidade afunda 25 cent\u00edmetros e est\u00e1dio que receber\u00e1 jogos da Copa do Mundo apresenta rachaduras"},"content":{"rendered":"\n<p>O tradicional Est\u00e1dio Azteca, na Cidade do M\u00e9xico, entrou em estado de alerta a menos de 32 dias da abertura da Copa do Mundo de 2026. O motivo s\u00e3o rachaduras identificadas no piso de concreto da estrutura, situa\u00e7\u00e3o que passou a ser monitorada de perto pelas autoridades mexicanas e tamb\u00e9m pela NASA por meio de imagens de sat\u00e9lite.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es divulgadas pelo jornal The Star, os problemas estruturais foram percebidos pela primeira vez durante o jogo de ida das quartas de final do Campeonato Mexicano. O caso gerou preocupa\u00e7\u00e3o devido \u00e0 proximidade do in\u00edcio da Copa do Mundo, j\u00e1 que o est\u00e1dio ser\u00e1 palco da cerim\u00f4nia de abertura e de partidas importantes do torneio.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"428\" data-id=\"43442\" src=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/estadio-azteca_Easy-Resize.com_-1140x476-1-1024x428.webp\" alt=\"\" class=\"wp-image-43442\" srcset=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/estadio-azteca_Easy-Resize.com_-1140x476-1-1024x428.webp 1024w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/estadio-azteca_Easy-Resize.com_-1140x476-1-300x125.webp 300w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/estadio-azteca_Easy-Resize.com_-1140x476-1-768x321.webp 768w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/estadio-azteca_Easy-Resize.com_-1140x476-1-750x313.webp 750w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/05\/estadio-azteca_Easy-Resize.com_-1140x476-1.webp 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Fifa<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>Especialistas apontam que o fen\u00f4meno pode estar ligado ao afundamento gradual de partes da Cidade do M\u00e9xico. Estudos da NASA indicam que determinadas regi\u00f5es da capital mexicana chegam a afundar cerca de 1,2 cent\u00edmetro por m\u00eas devido \u00e0 extra\u00e7\u00e3o excessiva de \u00e1gua subterr\u00e2nea. Em algumas \u00e1reas, a ag\u00eancia espacial j\u00e1 registrou rebaixamento acumulado de at\u00e9 25 cent\u00edmetros, um dos \u00edndices mais altos do mundo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Est\u00e1dio da abertura da Copa do Mundo apresenta problemas<\/h2>\n\n\n\n<p>Apesar das preocupa\u00e7\u00f5es, os organizadores da Fifa demonstram confian\u00e7a de que o est\u00e1dio estar\u00e1 totalmente preparado para receber os jogos do torneio. O Azteca ser\u00e1 palco da partida de abertura entre M\u00e9xico e \u00c1frica do Sul no dia 11 de junho, al\u00e9m da cerim\u00f4nia oficial que contar\u00e1 com apresenta\u00e7\u00f5es dos artistas Alejandro Fern\u00e1ndez, Belinda, Danny Ocean e Lila Downs.<\/p>\n\n\n\n<p>Al\u00e9m da abertura, o est\u00e1dio tamb\u00e9m receber\u00e1 confrontos como Uzbequist\u00e3o x Col\u00f4mbia e Rep\u00fablica Tcheca x M\u00e9xico, al\u00e9m de partidas das fases eliminat\u00f3rias da competi\u00e7\u00e3o. Considerado um dos palcos mais hist\u00f3ricos do futebol mundial, o Azteca j\u00e1 sediou finais de Copa do Mundo e segue como s\u00edmbolo esportivo do M\u00e9xico mesmo diante dos desafios estruturais atuais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O tradicional Est\u00e1dio Azteca, na Cidade do M\u00e9xico, entrou em estado de alerta a menos de 32 dias da abertura da Copa do Mundo de 2026. O motivo s\u00e3o rachaduras identificadas no piso de concreto da estrutura, situa\u00e7\u00e3o que passou a ser monitorada de perto pelas autoridades mexicanas e tamb\u00e9m pela NASA por meio de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":37512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-43440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/43440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=43440"}],"version-history":[{"count":1,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/43440\/revisions"}],"predecessor-version":[{"id":43443,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/43440\/revisions\/43443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/37512"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=43440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=43440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=43440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}