{"id":43522,"date":"2026-05-13T13:24:00","date_gmt":"2026-05-13T16:24:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=43522"},"modified":"2026-05-13T11:44:50","modified_gmt":"2026-05-13T14:44:50","slug":"cientistas-alertam-para-fenomeno-mais-intenso-dos-ultimos-140-anos-acontecendo-no-brasil-em-2026","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/cientistas-alertam-para-fenomeno-mais-intenso-dos-ultimos-140-anos-acontecendo-no-brasil-em-2026\/","title":{"rendered":"Cientistas alertam para fen\u00f4meno mais intenso dos \u00faltimos 140 anos acontecendo no Brasil em 2026"},"content":{"rendered":"\n<p>As mudan\u00e7as clim\u00e1ticas e a poss\u00edvel volta do fen\u00f4meno El Ni\u00f1o podem transformar 2026 em um dos anos mais cr\u00edticos j\u00e1 registrados para inc\u00eandios florestais no Brasil e no planeta. O alerta foi feito por cientistas internacionais, que apontam uma combina\u00e7\u00e3o perigosa entre o aquecimento global provocado pela a\u00e7\u00e3o humana e as condi\u00e7\u00f5es clim\u00e1ticas extremas associadas ao aquecimento das \u00e1guas do Oceano Pac\u00edfico.<\/p>\n\n\n\n<p>Pesquisadores afirmam que a temporada global de inc\u00eandios come\u00e7ou muito antes do habitual e j\u00e1 apresenta n\u00fameros hist\u00f3ricos. Dados do Sistema Global de Informa\u00e7\u00f5es sobre Inc\u00eandios mostram que cerca de 163 milh\u00f5es de hectares foram atingidos pelo fogo at\u00e9 o in\u00edcio de maio, volume muito superior \u00e0 m\u00e9dia registrada entre 2012 e 2025. Especialistas avaliam que o cen\u00e1rio pode piorar nos pr\u00f3ximos meses gra\u00e7as ao El Ni\u00f1o.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" data-id=\"34214\" src=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/02\/incendio-florestal-bsb2_mcamgo_abr_24082024-2_1-1024x613.webp\" alt=\"\" class=\"wp-image-34214\" srcset=\"https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/02\/incendio-florestal-bsb2_mcamgo_abr_24082024-2_1-1024x613.webp 1024w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/02\/incendio-florestal-bsb2_mcamgo_abr_24082024-2_1-300x179.webp 300w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/02\/incendio-florestal-bsb2_mcamgo_abr_24082024-2_1-768x459.webp 768w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/02\/incendio-florestal-bsb2_mcamgo_abr_24082024-2_1-750x449.webp 750w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/02\/incendio-florestal-bsb2_mcamgo_abr_24082024-2_1-1140x682.webp 1140w, https:\/\/correiodoestado.audiencelabs.com.br\/wp-content\/uploads\/2026\/02\/incendio-florestal-bsb2_mcamgo_abr_24082024-2_1.webp 1170w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Marcelo Camargo\/Ag\u00eancia Brasil <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>O fen\u00f4meno clim\u00e1tico \u00e9 caracterizado pelo aquecimento anormal das \u00e1guas do Oceano Pac\u00edfico e costuma provocar altera\u00e7\u00f5es severas no clima global. Dependendo da regi\u00e3o, o El Ni\u00f1o pode aumentar secas, ondas de calor e inc\u00eandios florestais, al\u00e9m de intensificar tempestades e enchentes. Cientistas destacam que, em um planeta j\u00e1 aquecido pelas emiss\u00f5es de gases do efeito estufa, os impactos tendem a ser ainda mais extremos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fen\u00f4meno El Ni\u00f1o pode trazer graves consequ\u00eancias ao Brasil<\/h2>\n\n\n\n<p>A climatologista Friederike Otto, do Imperial College de Londres, afirmou que o fen\u00f4meno natural por si s\u00f3 n\u00e3o seria motivo de preocupa\u00e7\u00e3o extrema, mas o problema est\u00e1 na combina\u00e7\u00e3o com as mudan\u00e7as clim\u00e1ticas causadas pela atividade humana. Segundo ela, o mundo vive um cen\u00e1rio de aquecimento acelerado, o que aumenta significativamente o risco de eventos clim\u00e1ticos sem precedentes.<\/p>\n\n\n\n<p>Especialistas tamb\u00e9m alertam que regi\u00f5es como Amaz\u00f4nia, Canad\u00e1, Austr\u00e1lia, Estados Unidos e partes da \u00c1sia podem enfrentar temporadas particularmente severas de inc\u00eandios e secas em 2026. A Organiza\u00e7\u00e3o Meteorol\u00f3gica Mundial deve divulgar ainda neste m\u00eas uma nova atualiza\u00e7\u00e3o sobre as perspectivas do El Ni\u00f1o, considerada fundamental para orientar governos e autoridades na prepara\u00e7\u00e3o contra poss\u00edveis desastres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As mudan\u00e7as clim\u00e1ticas e a poss\u00edvel volta do fen\u00f4meno El Ni\u00f1o podem transformar 2026 em um dos anos mais cr\u00edticos j\u00e1 registrados para inc\u00eandios florestais no Brasil e no planeta. O alerta foi feito por cientistas internacionais, que apontam uma combina\u00e7\u00e3o perigosa entre o aquecimento global provocado pela a\u00e7\u00e3o humana e as condi\u00e7\u00f5es clim\u00e1ticas extremas [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":43526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-43522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/43522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=43522"}],"version-history":[{"count":1,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/43522\/revisions"}],"predecessor-version":[{"id":43527,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/43522\/revisions\/43527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media\/43526"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=43522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=43522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=43522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}