{"id":43645,"date":"2026-05-14T10:42:26","date_gmt":"2026-05-14T13:42:26","guid":{"rendered":"https:\/\/mix.correiodoestado.com.br\/?p=43645"},"modified":"2026-05-14T10:42:27","modified_gmt":"2026-05-14T13:42:27","slug":"governo-visitara-as-casas-de-beneficiarios-de-pensoes-e-subsidios-sociais-com-advogados-para-verificar-isto-na-colombia","status":"publish","type":"post","link":"https:\/\/correiodoestado.com.br\/mix\/governo-visitara-as-casas-de-beneficiarios-de-pensoes-e-subsidios-sociais-com-advogados-para-verificar-isto-na-colombia\/","title":{"rendered":"Governo visitar\u00e1 as casas de benefici\u00e1rios de pens\u00f5es e subs\u00eddios sociais com advogados para verificar isto na Col\u00f4mbia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O governo da Col\u00f4mbia iniciou uma ampla opera\u00e7\u00e3o de fiscaliza\u00e7\u00e3o para revisar pagamentos de pens\u00f5es, subs\u00eddios e aux\u00edlios sociais em todo o pa\u00eds. O plano prev\u00ea o envio de equipes t\u00e9cnicas e administrativas para \u00e1reas urbanas e rurais com o objetivo de verificar presencialmente a situa\u00e7\u00e3o dos benefici\u00e1rios e identificar poss\u00edveis irregularidades nos programas sociais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o busca comparar os dados registrados nos sistemas p\u00fablicos colombianos com a realidade encontrada pelas equipes de campo. Durante as visitas, que contar\u00e3o com a presen\u00e7a de advogados e oficiais de Justi\u00e7a, ser\u00e3o analisados documentos, estado civil e condi\u00e7\u00f5es de vida dos benefici\u00e1rios para confirmar se os requisitos exigidos continuam sendo atendidos pelas pessoas que recebem os pagamentos do governo.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" data-id=\"43647\" src=\"https:\/\/mix.correiodoestado.com.br\/wp-content\/uploads\/2026\/05\/martelo_do_juiz_malhete-1024x613.webp\" alt=\"\" class=\"wp-image-43647\" srcset=\"https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2026\/05\/martelo_do_juiz_malhete-1024x613.webp 1024w, https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2026\/05\/martelo_do_juiz_malhete-300x179.webp 300w, https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2026\/05\/martelo_do_juiz_malhete-768x459.webp 768w, https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2026\/05\/martelo_do_juiz_malhete-750x449.webp 750w, https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2026\/05\/martelo_do_juiz_malhete-1140x682.webp 1140w, https:\/\/correiodoestado.com.br\/mix\/wp-content\/uploads\/2026\/05\/martelo_do_juiz_malhete.webp 1170w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9ditos: Qimono\/Pixabay<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m das inspe\u00e7\u00f5es presenciais, o governo colombiano tamb\u00e9m refor\u00e7ou o cruzamento de informa\u00e7\u00f5es entre \u00f3rg\u00e3os p\u00fablicos para detectar inconsist\u00eancias cadastrais. A medida pretende reduzir falhas em programas considerados mais vulner\u00e1veis a pagamentos indevidos, especialmente em regi\u00f5es com dificuldades de identifica\u00e7\u00e3o digital e grande dispers\u00e3o geogr\u00e1fica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Governo da Col\u00f4mbia vai subir a r\u00e9gua na fiscaliza\u00e7\u00e3o de benef\u00edcios <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Entre os benef\u00edcios que passar\u00e3o pela revis\u00e3o est\u00e3o pens\u00f5es administradas pela Colpensiones, aux\u00edlios pagos a idosos por programas sociais do Departamento de Prosperidade Social e repasses financeiros destinados a pessoas em situa\u00e7\u00e3o de vulnerabilidade. O foco principal \u00e9 evitar que pagamentos sejam feitos para pessoas falecidas, que tenham benefici\u00e1rios duplicados ou cidad\u00e3os que n\u00e3o atendam mais \u00e0s exig\u00eancias dos programas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando forem identificados pagamentos considerados irregulares, os benef\u00edcios poder\u00e3o ser suspensos at\u00e9 a atualiza\u00e7\u00e3o cadastral e an\u00e1lise completa da situa\u00e7\u00e3o do benefici\u00e1rio. O governo tamb\u00e9m prev\u00ea auditorias internas e externas nos casos mais complexos, al\u00e9m da possibilidade de cobran\u00e7a de reembolsos em situa\u00e7\u00f5es de fraude comprovada, como parte do esfor\u00e7o para garantir maior controle fiscal e sustentabilidade dos programas sociais do pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo da Col\u00f4mbia iniciou uma ampla opera\u00e7\u00e3o de fiscaliza\u00e7\u00e3o para revisar pagamentos de pens\u00f5es, subs\u00eddios e aux\u00edlios sociais em todo o pa\u00eds. O plano prev\u00ea o envio de equipes t\u00e9cnicas e administrativas para \u00e1reas urbanas e rurais com o objetivo de verificar presencialmente a situa\u00e7\u00e3o dos benefici\u00e1rios e identificar poss\u00edveis irregularidades nos programas sociais. [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":43646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-43645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/posts\/43645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/comments?post=43645"}],"version-history":[{"count":2,"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/posts\/43645\/revisions"}],"predecessor-version":[{"id":43707,"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/posts\/43645\/revisions\/43707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/media\/43646"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/media?parent=43645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/categories?post=43645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.com.br\/mix\/wp-json\/wp\/v2\/tags?post=43645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}