{"id":5385,"date":"2025-08-14T10:10:00","date_gmt":"2025-08-14T13:10:00","guid":{"rendered":"https:\/\/correiodoestado.audiencelabs.com.br\/?p=5385"},"modified":"2025-08-14T09:43:17","modified_gmt":"2025-08-14T12:43:17","slug":"cidade-catarinense-e-famosa-por-producao-de-vinho-com-raro-tipo-de-uva","status":"publish","type":"post","link":"https:\/\/correiodoestado.audiencelabs.com.br\/cidade-catarinense-e-famosa-por-producao-de-vinho-com-raro-tipo-de-uva\/","title":{"rendered":"Cidade catarinense \u00e9 famosa por produ\u00e7\u00e3o de vinho com raro tipo de uva"},"content":{"rendered":"\n<p>Embora n\u00e3o seja uma <a href=\"https:\/\/correiodoestado.com.br\/mix\/tribunal-de-justica-de-ms-abre-concurso-com-salario-inicial-de-r-322-mil\/\" target=\"_blank\" rel=\"noopener\">cidade <\/a>valorizada pelos turistas, Urussanga gera reconhecimento local por sua cultura da uva Goethe. Por ser uma fruta rara no Brasil, o munic\u00edpio de 21 mil habitantes, localizada no Sul de Santa Catarina, ganhou o status de capital do vinho, contando com v\u00e1rias vin\u00edcolas espalhadas pela regi\u00e3o.<\/p>\n\n\n\n<p>A princ\u00edpio, a uva Goethe chegou \u00e0 cidade no s\u00e9culo XIX, por interm\u00e9dio de imigrantes italianos. Diante da adapta\u00e7\u00e3o local, a fruta foi difundida por colonos de Santa Catarina, tornando Urussanga parte dos Vales da Uva Goethe, onde est\u00e1 toda a produ\u00e7\u00e3o do alimento e seus derivados.\u00a0Em resumo, o vales contemplam ainda as Pedras Grandes, Morro da Fuma\u00e7a, Cocal do Sul, Treze de Maio, Nova Veneza, I\u00e7ara e Orleans.<\/p>\n\n\n\n<p>Outrora denominada de Benedetta por seus habitantes, a cidade de Urussanga abra\u00e7a quatro das seis vin\u00edcolas da regi\u00e3o, sendo reconhecida por produ\u00e7\u00e3o superior a 60 hectares de vinhedos. Al\u00e9m de ser uma fruta at\u00edpica, a produ\u00e7\u00e3o do vinho ganha um tom de exclusividade ao passo que o clima, solo e quest\u00f5es pluviom\u00e9tricas n\u00e3o s\u00e3o vistos nos outros Estados.<a href=\"https:\/\/www.nsctotal.com.br\/noticias\/bispo-e-flagrado-de-calcinha-e-peruca-no-meio-da-rua-e-explica-motivo-investigacao-pessoal\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/2-4.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/2-4.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n\n\n\n<p>Para aqueles que desejam conhecer a regi\u00e3o, \u00e9 necess\u00e1rio se atentar a alguns detalhes antes de fazer as malas e desembarcar em Santa Catarina. Isso porque as frutas s\u00e3o disseminadas entre janeiro e fevereiro, enquanto os vinhos, geralmente, ficam prontos entre junho e julho. Posteriormente, os chamados vinhos tranquilos s\u00e3o utilizados para a elabora\u00e7\u00e3o dos frisantes, os vinhos com g\u00e1s.\u00a0<\/p>\n\n\n\n<p>Ao longo de oito meses, ocorre a segunda fermenta\u00e7\u00e3o, dentro da pr\u00f3pria garrafa, gerando o espumante. Como resultado da raridade da uva, os vinhos Goethe passam por an\u00e1lises de especialistas, que verificam sabor, cor e aroma antes de serem comercializados. O resultado final s\u00e3o vinhos brancos procurados por apreciadores de todo o planeta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que fazer na cidade al\u00e9m de apreciar vinhos?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/6-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a>Igreja matriz Nossa senhora da Concei\u00e7\u00e3o;<\/li>\n\n\n\n<li><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/13-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/13-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a>Chafariz com tartarugas na Pra\u00e7a Anita Garibaldi;<\/li>\n\n\n\n<li><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/6-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a>Centro Hist\u00f3rico de Urussanga;<\/li>\n\n\n\n<li>Parque Municipal Ado Cassetari Vieira;<\/li>\n\n\n\n<li>Igreja de S\u00e3o Gerv\u00e1sio e S\u00e3o Prot\u00e1sio;<\/li>\n\n\n\n<li><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/8-2.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/8-2.jpg\" target=\"_blank\" rel=\"noopener\"><\/a>Capela Santo Ant\u00f4nio, no Rio Caet\u00e9;<\/li>\n\n\n\n<li><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/12-1.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/12-1.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/6-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/13-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/13-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/9-2.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/9-2.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/11-1.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/11-1.jpg\" target=\"_blank\" rel=\"noopener\"><\/a>P\u00f3rtico de entrada na cidade com a tradicional Maria Fuma\u00e7a;<\/li>\n\n\n\n<li><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/14-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a><a href=\"https:\/\/img.nsctotal.com.br\/wp-content\/uploads\/2025\/05\/14-3.jpg\" target=\"_blank\" rel=\"noopener\"><\/a>Monumento ao garimpeiro de carv\u00e3o.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pouco conhecida no Brasil, cidade localizada no sul de Santa Catarina det\u00e9m comercializa\u00e7\u00e3o de vinhos oriundos de uvas raras<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5385","post","type-post","status-publish","format-standard","hentry","category-mix"],"_links":{"self":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/5385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/comments?post=5385"}],"version-history":[{"count":1,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/5385\/revisions"}],"predecessor-version":[{"id":5388,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/posts\/5385\/revisions\/5388"}],"wp:attachment":[{"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/media?parent=5385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/categories?post=5385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodoestado.audiencelabs.com.br\/wp-json\/wp\/v2\/tags?post=5385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}